{"id":19904,"date":"2026-02-16T12:35:28","date_gmt":"2026-02-16T11:35:28","guid":{"rendered":"https:\/\/nsfgames.com\/stellenangebot-linienkoordinator\/"},"modified":"2026-05-06T15:42:05","modified_gmt":"2026-05-06T13:42:05","slug":"stellenangebot-linienkoordinator","status":"publish","type":"post","link":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/","title":{"rendered":"Stellenangebot: Linienkoordinator"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19904\" class=\"elementor elementor-19904\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d5ff8d e-flex e-con-boxed e-con e-parent\" data-id=\"6d5ff8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-208eabb elementor-widget elementor-widget-text-editor\" data-id=\"208eabb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Was macht die Nederlandse Spellenfabriek B.V.?<\/strong><br \/>\nDie Nederlandse Spellenfabriek B.V. (NSF) ist ein erfolgreicher und dynamischer Hersteller von hochwertigen Luxusverpackungen, Puzzles und Brettspielen wie beispielsweise Jan van Haasteren, Stratego, Carcassonne, Mens Erger Je Niet und Monopoly. Wir wurden 1950 gegr\u00fcndet und geh\u00f6ren zur De Monchy Groep, zu der auch das Unternehmen Koninklijke Jumbo geh\u00f6rt. Seit 2006 hat NSF seinen Sitz in Medemblik und besch\u00e4ftigt rund 120 Mitarbeiter. Wir produzieren j\u00e4hrlich Millionen von Spielen und Puzzles. Damit geh\u00f6ren wir in Europa zu den Top 5 der Spielehersteller und weltweit zu den Top 3 der Puzzlehersteller. In den letzten 5 Jahren wurde viel in Maschinen, Neubauten, IT und Personal investiert, sodass wir das erwartete zuk\u00fcnftige Wachstum verantwortungsbewusst bew\u00e4ltigen k\u00f6nnen. Die Kultur in unserem Werk l\u00e4sst sich als informell, engagiert, sachlich und ergebnisorientiert beschreiben.<\/p>\n<p>Passt diese service- und qualit\u00e4tsorientierte Einstellung zu Ihnen? Dann lesen Sie schnell weiter, denn vielleicht produzieren Sie bald gemeinsam mit uns eines der vielen bekannten Brettspiele und Puzzles.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Stellenbeschreibung<br \/>\n<\/strong>Als Linienkoordinator haben Sie umfangreiche Berufserfahrung in einer leitenden Position in einem Produktionsunternehmen gesammelt. Sie verf\u00fcgen \u00fcber Kenntnisse und Erfahrungen mit Lean-Manufacturing-Verbesserungstechniken und sorgen f\u00fcr einen effizienten Produktionsprozess. Dadurch sind Sie in der Lage, die folgenden Aufgaben und Verantwortlichkeiten zu \u00fcbernehmen:<\/p>\n<ul>\n<li>Sicherheit, Ordnung und Sauberkeit (5S);<\/li>\n<li>Effizienz der Bediener, der Produktionsmitarbeiter und der Produktionsmittel;<\/li>\n<li>Vermeidung von Verschwendung (Transport, Lagerbestand, \u00dcberbearbeitung, \u00dcberproduktion, Wartezeiten, Fehler, Bewegung, Talent);<\/li>\n<li>Umstellung der Maschinen an der Fertigungslinie;<\/li>\n<li>Rechtzeitiges Erkennen, Analysieren, Beheben und\/oder Melden von St\u00f6rungen\/Abweichungen;<\/li>\n<li>Kontrolle der Produktion und \u00dcberwachung der Auftragsabwicklung;<\/li>\n<li>\u00dcberwachung der t\u00e4glichen Kontinuit\u00e4t und Sicherstellung maximaler Effizienz in den Produktionsprozessen;<\/li>\n<li>\u00dcberwachung der Produktqualit\u00e4t;<\/li>\n<li>Koordination von Verbesserungsprojekten der Linie;<\/li>\n<li>F\u00fchrung des stellvertretenden Linienkoordinators, der Bediener und der Montagearbeiter;<\/li>\n<\/ul>\n<ul>\n<li>Einstellung der Produktion, wenn Kundenanforderungen oder Sicherheitsvorschriften nicht erf\u00fcllt werden k\u00f6nnen;<\/li>\n<li>Sicherstellung einer guten Arbeitsatmosph\u00e4re. Durchsetzung der Arbeitsschutzrichtlinien, Hausordnung und Normen und Werte;<\/li>\n<li>Beurteilung der Mitarbeiter; Mitarbeitergespr\u00e4che<\/li>\n<\/ul>\n<ul>\n<li>Durchf\u00fchrung von Toolbox-Meetings;<\/li>\n<li>\u00dcberwachung der Einhaltung der Arbeitsstandards (Arbeitsanweisungen f\u00fcr Maschinen\/Prozesse\/Wartung);<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wir erwarten f\u00fcr diese Position:<\/strong><\/p>\n<ul>\n<li>Sie verf\u00fcgen \u00fcber mindestens 2 Jahre einschl\u00e4gige Berufserfahrung in einer F\u00fchrungsposition;<\/li>\n<li>Technisches Verst\u00e4ndnis und Erfahrung mit der Umstellung von Produktionsmaschinen;<\/li>\n<li>Kenntnisse und Erfahrung mit Lean-Manufacturing-Verbesserungstechniken, Sicherung von Verbesserungen<\/li>\n<li>Ausgezeichnete Kommunikationsf\u00e4higkeiten;<\/li>\n<li>Gute Beherrschung der niederl\u00e4ndischen und englischen Sprache;<\/li>\n<li>Verf\u00fcgen \u00fcber folgende Kompetenzen: kaufm\u00e4nnisches, taktisches und operatives Verst\u00e4ndnis, analytische F\u00e4higkeiten, \u00dcberzeugungskraft, Sie k\u00f6nnen unter Zeitdruck arbeiten und verf\u00fcgen \u00fcber ausgezeichnete Kommunikationsf\u00e4higkeiten. Dar\u00fcber hinaus sind Sie selbstbewusst und einfach ein angenehmer Mensch.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Was bietet Ihnen die Nederlandse Spellenfabriek?<br \/>\n<\/strong>Wir bieten Ihnen eine Stelle in einem vielf\u00e4ltigen und herausfordernden Umfeld. Sie arbeiten jeden Tag mit sch\u00f6nen technischen Maschinen, in die wir kontinuierlich investieren\/erneuern. T\u00e4glich sehen Sie die sch\u00f6nsten Brettspiele und Puzzles. Sie k\u00f6nnen Ihre Stelle gemeinsam mit Ihrem Vorgesetzten entsprechend den W\u00fcnschen unseres Unternehmens weiter gestalten. Dar\u00fcber hinaus bieten wir Ihnen:<\/p>\n<ul>\n<li>Gutes Gehalt gem\u00e4\u00df dem Kartonnage-Tarifvertrag zwischen 2.849 \u20ac und 3.248 \u20ac auf Basis von 40 Stunden pro Woche;<\/li>\n<li>Gewinnbeteiligungsregelung;<\/li>\n<li>Altersvorsorge;<\/li>\n<li>Reisekostenverg\u00fctung;<\/li>\n<li>Sport mit Rabatt \u00fcber Bedrijfsfitness Nederland;<\/li>\n<li>Fahrradplan;<\/li>\n<li>Aussicht auf einen unbefristeten Vertrag;<\/li>\n<li>Und nicht unwichtig: Unterhaltsame und gesellige Betriebsausfl\u00fcge.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Arbeitszeiten:<\/strong><\/p>\n<ul>\n<li>Tagschicht: 7:30 bis 16:30 Uhr.<\/li>\n<li>Fr\u00fchschicht (Schicht): 6:00 bis 14:30 Uhr (falls zutreffend).<\/li>\n<li>Sp\u00e4tschicht (Schicht): 14:30 bis 23:00 Uhr (falls zutreffend).<\/li>\n<\/ul>\n<p>Wachsen Sie mit uns als Linienkoordinator bei Nederlandse Spellenfabriek. Spricht Sie das an? Dann bewerben Sie sich gleich!<\/p>\n<p><strong>Bewerbungsverfahren<\/strong><\/p>\n<p>Wenn Sie weitere Informationen w\u00fcnschen oder Fragen zu dieser Stelle haben, wenden Sie sich bitte per E-Mail an Frank oder Esther unter pz@nsfgames.com. Selbstverst\u00e4ndlich k\u00f6nnen Sie auch direkt Ihren Lebenslauf und Ihr Anschreiben an diese Adresse senden. M\u00f6chten Sie wissen, wie Ihr neuer Arbeitsplatz aussieht? Besuchen Sie unsere Website: https:\/\/nsfgames.com\/de\/video\/<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener an, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212,187],"tags":[],"class_list":["post-19904","post","type-post","status-publish","format-standard","hentry","category-no-category","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stellenangebot: Linienkoordinator - NSFgames.com<\/title>\n<meta name=\"description\" content=\"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stellenangebot: Linienkoordinator - NSFgames.com\" \/>\n<meta property=\"og:description\" content=\"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/\" \/>\n<meta property=\"og:site_name\" content=\"NSFgames.com\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-16T11:35:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:42:05+00:00\" \/>\n<meta name=\"author\" content=\"Frank Putto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank Putto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/\"},\"author\":{\"name\":\"Frank Putto\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#\\\/schema\\\/person\\\/1d83638875a21b9196d06e4ef7b77b8c\"},\"headline\":\"Stellenangebot: Linienkoordinator\",\"datePublished\":\"2026-02-16T11:35:28+00:00\",\"dateModified\":\"2026-05-06T13:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/\"},\"wordCount\":631,\"publisher\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#organization\"},\"articleSection\":[\"No Category\",\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/\",\"url\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/\",\"name\":\"Stellenangebot: Linienkoordinator - NSFgames.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#website\"},\"datePublished\":\"2026-02-16T11:35:28+00:00\",\"dateModified\":\"2026-05-06T13:42:05+00:00\",\"description\":\"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/stellenangebot-linienkoordinator\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stellenangebot: Linienkoordinator\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#website\",\"url\":\"https:\\\/\\\/nsfgames.com\\\/\",\"name\":\"NSFgames.com\",\"description\":\"Boardgames and Puzzles\",\"publisher\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#organization\"},\"alternateName\":\"Nederlandse Spellenfabriek\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nsfgames.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#organization\",\"name\":\"NSFgames.com\",\"url\":\"https:\\\/\\\/nsfgames.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nsfgames.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/NSF-logo-170622-03.png\",\"contentUrl\":\"https:\\\/\\\/nsfgames.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/NSF-logo-170622-03.png\",\"width\":186,\"height\":43,\"caption\":\"NSFgames.com\"},\"image\":{\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nsfgames.com\\\/#\\\/schema\\\/person\\\/1d83638875a21b9196d06e4ef7b77b8c\",\"name\":\"Frank Putto\",\"url\":\"https:\\\/\\\/nsfgames.com\\\/de\\\/author\\\/frank-putto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stellenangebot: Linienkoordinator - NSFgames.com","description":"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/","og_locale":"de_DE","og_type":"article","og_title":"Stellenangebot: Linienkoordinator - NSFgames.com","og_description":"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.","og_url":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/","og_site_name":"NSFgames.com","article_published_time":"2026-02-16T11:35:28+00:00","article_modified_time":"2026-05-06T13:42:05+00:00","author":"Frank Putto","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Frank Putto","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/#article","isPartOf":{"@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/"},"author":{"name":"Frank Putto","@id":"https:\/\/nsfgames.com\/#\/schema\/person\/1d83638875a21b9196d06e4ef7b77b8c"},"headline":"Stellenangebot: Linienkoordinator","datePublished":"2026-02-16T11:35:28+00:00","dateModified":"2026-05-06T13:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/"},"wordCount":631,"publisher":{"@id":"https:\/\/nsfgames.com\/#organization"},"articleSection":["No Category","Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/","url":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/","name":"Stellenangebot: Linienkoordinator - NSFgames.com","isPartOf":{"@id":"https:\/\/nsfgames.com\/#website"},"datePublished":"2026-02-16T11:35:28+00:00","dateModified":"2026-05-06T13:42:05+00:00","description":"Die Nederlandse Spellenfabriek sucht einen Linienkoordinator mit Erfahrung in der Produktion und im Lean Manufacturing. Sie leiten die Bediener und den stellvertretenden Linienkoordinator, \u00fcberwachen die Effizienz, verhindern Verschwendung, koordinieren Verbesserungsprojekte und gew\u00e4hrleisten Qualit\u00e4t und Sicherheit. Dar\u00fcber hinaus beheben Sie St\u00f6rungen und sorgen f\u00fcr optimale Produktionsprozesse.","breadcrumb":{"@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nsfgames.com\/de\/stellenangebot-linienkoordinator\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nsfgames.com\/de\/"},{"@type":"ListItem","position":2,"name":"Stellenangebot: Linienkoordinator"}]},{"@type":"WebSite","@id":"https:\/\/nsfgames.com\/#website","url":"https:\/\/nsfgames.com\/","name":"NSFgames.com","description":"Boardgames and Puzzles","publisher":{"@id":"https:\/\/nsfgames.com\/#organization"},"alternateName":"Nederlandse Spellenfabriek","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nsfgames.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nsfgames.com\/#organization","name":"NSFgames.com","url":"https:\/\/nsfgames.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nsfgames.com\/#\/schema\/logo\/image\/","url":"https:\/\/nsfgames.com\/wp-content\/uploads\/2017\/06\/NSF-logo-170622-03.png","contentUrl":"https:\/\/nsfgames.com\/wp-content\/uploads\/2017\/06\/NSF-logo-170622-03.png","width":186,"height":43,"caption":"NSFgames.com"},"image":{"@id":"https:\/\/nsfgames.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nsfgames.com\/#\/schema\/person\/1d83638875a21b9196d06e4ef7b77b8c","name":"Frank Putto","url":"https:\/\/nsfgames.com\/de\/author\/frank-putto\/"}]}},"_links":{"self":[{"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/posts\/19904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/comments?post=19904"}],"version-history":[{"count":1,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/posts\/19904\/revisions"}],"predecessor-version":[{"id":19905,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/posts\/19904\/revisions\/19905"}],"wp:attachment":[{"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/media?parent=19904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/categories?post=19904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nsfgames.com\/de\/wp-json\/wp\/v2\/tags?post=19904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}